{"id":3833,"date":"2021-02-09T12:56:40","date_gmt":"2021-02-09T12:56:40","guid":{"rendered":"http:\/\/braunvie.cyon.link\/geschaeftsbericht\/"},"modified":"2026-03-30T11:30:13","modified_gmt":"2026-03-30T09:30:13","slug":"geschaeftsbericht","status":"publish","type":"page","link":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/","title":{"rendered":"Rapporto di gestione"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-modular.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3833","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rapporto di gestione | Braunvieh<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapporto di gestione | Braunvieh\" \/>\n<meta property=\"og:description\" content=\"&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/\" \/>\n<meta property=\"og:site_name\" content=\"Braunvieh\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T09:30:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/it\\\/geschaeftsbericht\\\/\",\"url\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/it\\\/geschaeftsbericht\\\/\",\"name\":\"Rapporto di gestione | Braunvieh\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/en\\\/#website\"},\"datePublished\":\"2021-02-09T12:56:40+00:00\",\"dateModified\":\"2026-03-30T09:30:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/it\\\/geschaeftsbericht\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homepage.braunvieh.ch\\\/it\\\/geschaeftsbericht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/it\\\/geschaeftsbericht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapporto di gestione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/en\\\/\",\"name\":\"Braunvieh\",\"description\":\"Alles \u00fcber Braunvieh und die Braunviehzucht. Sowie den Braunviehzuchtverband als modernes Dienstleistungsunternehmen.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homepage.braunvieh.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapporto di gestione | Braunvieh","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/","og_locale":"it_IT","og_type":"article","og_title":"Rapporto di gestione | Braunvieh","og_description":"&nbsp;","og_url":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/","og_site_name":"Braunvieh","article_modified_time":"2026-03-30T09:30:13+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/","url":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/","name":"Rapporto di gestione | Braunvieh","isPartOf":{"@id":"https:\/\/homepage.braunvieh.ch\/en\/#website"},"datePublished":"2021-02-09T12:56:40+00:00","dateModified":"2026-03-30T09:30:13+00:00","breadcrumb":{"@id":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/homepage.braunvieh.ch\/it\/geschaeftsbericht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homepage.braunvieh.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Rapporto di gestione"}]},{"@type":"WebSite","@id":"https:\/\/homepage.braunvieh.ch\/en\/#website","url":"https:\/\/homepage.braunvieh.ch\/en\/","name":"Braunvieh","description":"Alles \u00fcber Braunvieh und die Braunviehzucht. Sowie den Braunviehzuchtverband als modernes Dienstleistungsunternehmen.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homepage.braunvieh.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/pages\/3833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/comments?post=3833"}],"version-history":[{"count":13,"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/pages\/3833\/revisions"}],"predecessor-version":[{"id":32533,"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/pages\/3833\/revisions\/32533"}],"wp:attachment":[{"href":"https:\/\/homepage.braunvieh.ch\/it\/wp-json\/wp\/v2\/media?parent=3833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}